{"id":225683,"date":"2026-04-25T01:52:18","date_gmt":"2026-04-25T01:52:18","guid":{"rendered":"https:\/\/e-compare.com.br\/wp\/2026\/04\/flat-franca-lona-listrada-azul-e-off-white-e-couro-caramelo-azul-39-us-10\/"},"modified":"2026-04-25T01:52:18","modified_gmt":"2026-04-25T01:52:18","slug":"flat-franca-lona-listrada-azul-e-off-white-e-couro-caramelo-azul-39-us-10","status":"publish","type":"post","link":"https:\/\/e-compare.com.br\/wp\/2026\/04\/flat-franca-lona-listrada-azul-e-off-white-e-couro-caramelo-azul-39-us-10\/","title":{"rendered":"Flat Franca Lona Listrada Azul e Off White e Couro Caramelo-Azul \/ 39 (US 10)"},"content":{"rendered":"<div class='booster-block booster-read-block'>\n                <div class=\"twp-read-time\">\n                \t<i class=\"booster-icon twp-clock\"><\/i> <span>Pre\u00e7os V\u00e1lidos h\u00e1 mais de:<\/span>31 dias                <\/div>\n\n            <\/div><p><img decoding=\"async\" src=\"https:\/\/cdn.shopify.com\/s\/files\/1\/0890\/3662\/0090\/files\/L110-FRAN-INDI-2426_1.webp?v=1764168015\" alt=\"Flat Franca Lona Listrada Azul e Off White e Couro Caramelo-Azul \/ 39 (US 10)\" \/><br \/>\nUma flat minimalista que \u00e9 a cara da trend boho chic, Franca combina couro macio com lona listrada, destacada pelo detalhe em metal dourado. O resultado \u00e9 um visual leve, fresco e cheio de personalidade.Com palmilha acolchoada e solado em couro premium, \u00e9 a escolha ideal para os dias quentes \u2013 f\u00e1cil de usar com vestidos fluidos, alfaiataria leve ou jeans. Detalhes do produto:  Azul-marinho, off white e caramelo Cabedal em lona e couro Forro em couro Bico redondo aberto Metais dourados Sola de couro finamente trabalhada para melhor suporte, durabilidade e conforto Remova o pl\u00e1stico protetor da sola antes de usar o sapato Palmilha Larroud\u00e9 Cloud acolchoada com espuma tecnol\u00f3gica e logo em hot stamp Feito \u00e0 m\u00e3o no Brasil SKU: L110-FRAN-INDI-2426<\/p>\n<hr>\n<h2>Categoria: Rasteiras, Bege, In Stock, New Flats, Pronta Entrega, New In, Sale, Novidades, 34, 38, 40, Black Friday, Summer 2026, Dia das M\u00e3es Larroud\u00e9, All 500, All 400, All 600, All 700, _swatch-family: FRANCA FLAT<\/h2>\n<h3>O pre\u00e7o de Flat Franca Lona Listrada Azul e Off White e Couro Caramelo-Azul \/ 39 (US 10) que conseguimos extrair do sistema no dia acima era de <strong>R$ 950<\/strong>.<\/h3>\n<p>Se ocorreu mudan\u00e7a de pre\u00e7o, pode ser verificado no seguinte link: <a href=\"https:\/\/www.awin1.com\/pclick.php?p=44185755025&#038;a=690303&#038;m=123644\" target=\"_blank\" rel=\"noopener sponsored\"><img decoding=\"async\" src=\"https:\/\/ui.awin.com\/images\/upload\/merchant\/profile\/123644.png\" alt=\"Flat Franca Lona Listrada Azul e Off White e Couro Caramelo-Azul \/ 39 (US 10)\" \/> &#8211; disponibilizado pelas lojas  Larroud\u00e9 BR<\/a><\/p>\n<hr>\n<h4>Aproveite e pesquise o pre\u00e7o deste produto em dezenas de lojas dos marketplaces abaixo:<\/h4>\n<p><a href=\"https:\/\/www.magazinevoce.com.br\/magazineezu\/busca\/Flat Franca Lona Listrada Azul e Off White e Couro Caramelo-Azul \/ 39 (US 10)\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/mvc.mlcdn.com.br\/ad\/2503_superofertas.png\" alt=\"Pesquise no Magazine eZu\" \/> &#8211; da Parceria MAGALU<\/a>.<\/p>\n<hr \/>\n<p><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-5987304558705355\" crossorigin=\"anonymous\"><\/script><br \/>\n<ins class=\"adsbygoogle\" style=\"display: block;\" data-ad-format=\"autorelaxed\" data-ad-client=\"ca-pub-5987304558705355\" data-ad-slot=\"6675008826\"><\/ins><br \/>\n<script>\n     (adsbygoogle = window.adsbygoogle || ).push();\n<\/script><\/p>\n<hr \/>\n<p>Ainda n\u00e3o encontrou a melhor op\u00e7\u00e3o de compra? Oferecemos mais uma possibilidade de <strong>busca<\/strong> mais ampla para <a href=\"https:\/\/ecompare.com.br\/lojas\/resultados-da-pesquisa\/?q=Flat Franca Lona Listrada Azul e Off White e Couro Caramelo-Azul \/ 39 (US 10)#gsc.tab=0&amp;gsc.q=Flat Franca Lona Listrada Azul e Off White e Couro Caramelo-Azul \/ 39 (US 10)&amp;gsc.page=1\" target=\"_blank\" rel=\"noopener\">Flat Franca Lona Listrada Azul e Off White e Couro Caramelo-Azul \/ 39 (US 10), clique e continue <strong>pesquisando&#8230;<\/strong><\/a><\/p>\n<hr \/>\n<p>C\u00f3digo: 4418575502552167116521786BRL950950123644BRL114087<\/p>\n        <div class=\"booster-block booster-reactions-block\">\n            <div class=\"twp-reactions-icons\">\n                \n                <div class=\"twp-reacts-wrap\">\n                    <a react-data=\"be-react-1\" post-id=\"225683\" class=\"be-face-icons un-reacted\" href=\"javascript:void(0)\">\n                        <img decoding=\"async\" src=\"https:\/\/e-compare.com.br\/wp\/wp-content\/plugins\/booster-extension\/\/assets\/icon\/happy.svg\" alt=\"Happy\">\n                    <\/a>\n                    <div class=\"twp-reaction-title\">\n                        Happy                    <\/div>\n                    <div class=\"twp-count-percent\">\n                        \n                                                    <span class=\"twp-react-count\">0<\/span>\n                                            <\/div>\n                <\/div>\n\n                <div class=\"twp-reacts-wrap\">\n                    <a react-data=\"be-react-2\" post-id=\"225683\" class=\"be-face-icons un-reacted\" href=\"javascript:void(0)\">\n                        <img decoding=\"async\" src=\"https:\/\/e-compare.com.br\/wp\/wp-content\/plugins\/booster-extension\/\/assets\/icon\/sad.svg\" alt=\"Sad\">\n                    <\/a>\n                    <div class=\"twp-reaction-title\">\n                        Sad                    <\/div>\n                    <div class=\"twp-count-percent\">\n                                                                            <span class=\"twp-react-count\">0<\/span>\n                                            <\/div>\n                <\/div>\n\n                <div class=\"twp-reacts-wrap\">\n                    <a react-data=\"be-react-3\" post-id=\"225683\" class=\"be-face-icons un-reacted\" href=\"javascript:void(0)\">\n                        <img decoding=\"async\" src=\"https:\/\/e-compare.com.br\/wp\/wp-content\/plugins\/booster-extension\/\/assets\/icon\/excited.svg\" alt=\"Excited\">\n                    <\/a>\n                    <div class=\"twp-reaction-title\">\n                        Excited                    <\/div>\n                    <div class=\"twp-count-percent\">\n                                                                            <span class=\"twp-react-count\">0<\/span>\n                                            <\/div>\n                <\/div>\n\n                <div class=\"twp-reacts-wrap\">\n                    <a react-data=\"be-react-6\" post-id=\"225683\" class=\"be-face-icons un-reacted\" href=\"javascript:void(0)\">\n                        <img decoding=\"async\" src=\"https:\/\/e-compare.com.br\/wp\/wp-content\/plugins\/booster-extension\/\/assets\/icon\/sleepy.svg\" alt=\"Sleepy\">\n                    <\/a>\n                    <div class=\"twp-reaction-title\">\n                        Sleepy                    <\/div>\n                    <div class=\"twp-count-percent\">\n                        \n                                                    <span class=\"twp-react-count\">0<\/span>\n                                            <\/div>\n                <\/div>\n\n                <div class=\"twp-reacts-wrap\">\n                    <a react-data=\"be-react-4\" post-id=\"225683\" class=\"be-face-icons un-reacted\" href=\"javascript:void(0)\">\n                        <img decoding=\"async\" src=\"https:\/\/e-compare.com.br\/wp\/wp-content\/plugins\/booster-extension\/\/assets\/icon\/angry.svg\" alt=\"Angry\">\n                    <\/a>\n                    <div class=\"twp-reaction-title\">Angry<\/div>\n                    <div class=\"twp-count-percent\">\n                                                                            <span class=\"twp-react-count\">0<\/span>\n                        \n                    <\/div>\n                <\/div>\n\n                <div class=\"twp-reacts-wrap\">\n                    <a react-data=\"be-react-5\" post-id=\"225683\" class=\"be-face-icons un-reacted\" href=\"javascript:void(0)\">\n                        <img decoding=\"async\" src=\"https:\/\/e-compare.com.br\/wp\/wp-content\/plugins\/booster-extension\/\/assets\/icon\/surprise.svg\" alt=\"Surprise\">\n                    <\/a>\n                    <div class=\"twp-reaction-title\">Surprise<\/div>\n                    <div class=\"twp-count-percent\">\n                                                                            <span class=\"twp-react-count\">0<\/span>\n                                            <\/div>\n                <\/div>\n\n            <\/div>\n        <\/div>\n\n    ","protected":false},"excerpt":{"rendered":"<p>R$ 950 nas lojas <a href=\"https:\/\/www.awin1.com\/pclick.php?p=44185755025&#038;a=690303&#038;m=123644\" target=\"_blank\" rel=\"sponsored\">Larroud\u00e9 BR<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[198],"tags":[1289,5330],"class_list":["post-225683","post","type-post","status-publish","format-standard","hentry","category-produtos","tag-1289","tag-larroude-br"],"_links":{"self":[{"href":"https:\/\/e-compare.com.br\/wp\/wp-json\/wp\/v2\/posts\/225683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e-compare.com.br\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e-compare.com.br\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e-compare.com.br\/wp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/e-compare.com.br\/wp\/wp-json\/wp\/v2\/comments?post=225683"}],"version-history":[{"count":0,"href":"https:\/\/e-compare.com.br\/wp\/wp-json\/wp\/v2\/posts\/225683\/revisions"}],"wp:attachment":[{"href":"https:\/\/e-compare.com.br\/wp\/wp-json\/wp\/v2\/media?parent=225683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e-compare.com.br\/wp\/wp-json\/wp\/v2\/categories?post=225683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e-compare.com.br\/wp\/wp-json\/wp\/v2\/tags?post=225683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}